{"id":6735,"date":"2024-03-11T12:38:55","date_gmt":"2024-03-11T12:38:55","guid":{"rendered":"http:\/\/www.olidemallorca.es\/participa-a-oleotapa-2024-el-concurs-de-tapes-amb-oli-de-mallorca-per-a-cuiners-professionals-2\/"},"modified":"2024-03-11T12:59:11","modified_gmt":"2024-03-11T12:59:11","slug":"participa-a-oleotapa-2024-el-concurs-de-tapes-amb-oli-de-mallorca-per-a-cuiners-professionals","status":"publish","type":"post","link":"https:\/\/www.olidemallorca.es\/en\/participa-a-oleotapa-2024-el-concurs-de-tapes-amb-oli-de-mallorca-per-a-cuiners-professionals\/","title":{"rendered":"Participa a Oleotapa 2024, el concurs de tapes amb Oli de Mallorca per a cuiners professionals"},"content":{"rendered":"<p><a href=\"https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria-.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-6730\" src=\"https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria--1024x1024.jpg\" alt=\"oleotapa-2024-convocatoria\" width=\"604\" height=\"604\" srcset=\"https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria--1024x1024.jpg 1024w, https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria--150x150.jpg 150w, https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria--300x300.jpg 300w, https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria--768x768.jpg 768w, https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/Oleotapa-2024-convocatoria-.jpg 1080w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>El Consell Regulador de la Denominaci\u00f3 d\u2019Origen Oli de Mallorca convoca el concurs per a cuiners professionals Oleotapa 2024, certamen que premiar\u00e0 la tapa elaborada amb Oli de Mallorca que millor expressi el paper de l&#8217;Oli d&#8217;Oliva Verge Extra com a ingredient de valor per al sabor i aroma finals.<\/p>\n<p>El cuiner guanyador del concurs rebr\u00e0 una selecci\u00f3 d\u2019Oli d\u2019Oliva Verge Extra amb segell de qualitat Oli de Mallorca, 1 entrada de congressista a Madrid Fusion 2025, un bo de 250 euros per compres al Mercat de l\u2019Olivar i l\u2019oportunitat de participar en accions de la D.O Oli de Mallorca. El segon i tercer classificats obtindran una selecci\u00f3 d\u2019OOVE i bons de compra al Mercat de l\u2019Olivar.<\/p>\n<p>El concurs Oleotapa compta un any m\u00e9s amb el suport del Mercat de l\u2019Olivar, Escola d\u2019Hoteleria de les Illes Balears, l\u2019Asociaci\u00f3n de Cocineros Afincados en las Islas Baleares, aix\u00ed com del Fons de Garantia Agr\u00e0ria i Pesquera de les Illes Balears, Ministerio de Agricultura, Pesca y Alimentaci\u00f3n i Fons Europeu Agr\u00edcola de Desenvolupament Rural.<\/p>\n<p>Els cuiners disposen fins al 3 d&#8217;abril per inscriure la seva tapa amb Oli de Mallorca al seg\u00fcent <strong><span style=\"color: #808000;\"><a style=\"color: #808000;\" href=\"https:\/\/forms.gle\/ovjz9PVPfWfzBkNG6\" target=\"_blank\">formulari d&#8217;inscripci\u00f3<\/a><\/span><\/strong>. D&#8217;entre totes les propostes rebudes sortiran els finalistes que competiran dia 15 d&#8217;abril a la final que tindr\u00e0 lloc a l\u2019Escola d\u2019Hoteleria de les Illes Balears.<\/p>\n<p>Podeu consultar aqu\u00ed les <span style=\"color: #808000;\"><strong><a style=\"color: #808000;\" href=\"https:\/\/www.olidemallorca.es\/wp-content\/uploads\/2024\/03\/oleotapa_24_bases_concurs.pdf\" target=\"_blank\">bases Oleotapa 2024<\/a><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; El Consell Regulador de la Denominaci\u00f3 d\u2019Origen Oli de Mallorca convoca el concurs per a cuiners professionals Oleotapa 2024, certamen que premiar\u00e0 la tapa elaborada amb Oli de Mallorca que millor expressi el paper de l&#8217;Oli d&#8217;Oliva Verge [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6733,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[42],"tags":[2546,3484,2086,3485,3486],"class_list":["post-6735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-chef-en","tag-cocinero-en","tag-cuiner-en","tag-oleotapa-2024-en","tag-organoleptic-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/posts\/6735"}],"collection":[{"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/comments?post=6735"}],"version-history":[{"count":1,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/posts\/6735\/revisions"}],"predecessor-version":[{"id":6743,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/posts\/6735\/revisions\/6743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/media\/6733"}],"wp:attachment":[{"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/media?parent=6735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/categories?post=6735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.olidemallorca.es\/en\/wp-json\/wp\/v2\/tags?post=6735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}